{"id":2881,"date":"2025-06-26T17:10:49","date_gmt":"2025-06-26T15:10:49","guid":{"rendered":"https:\/\/www.pulp-tec.com\/imballaggio-del-vino\/"},"modified":"2026-04-09T18:48:35","modified_gmt":"2026-04-09T16:48:35","slug":"imballaggio-del-vino","status":"publish","type":"page","link":"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-standard\/imballaggio-del-vino\/","title":{"rendered":"Imballaggio del vino"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;1%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h1&#8243; text_color=&#8221;#719fb9&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Imballaggio del vino&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3 class=\"hl-sub text-pulpdarkblue\">Imballaggio protettivo ecologico per vini e liquori<\/h3>\n<p>La nostra vasta gamma di confezioni di vino, liquori e champagne &#8211; incluse opzioni come il portabottiglie e la cassetta per il vino &#8211; \u00e8 approvata da Postal &amp; DPD e disponibile il giorno successivo in magazzino in confezioni di dimensioni singole, doppie, triple, quattro, sei e dodici.<\/p>\n<p>Gli imballaggi per vino Pulp offrono una protezione impareggiabile grazie ai nostri robusti inserti in polpa di cellulosa e ai cartoni esterni a doppia parete, progettati appositamente per proteggere le tue bottiglie durante il trasporto.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;593&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; bottom_padding=&#8221;8%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3 class=\"\">Vantaggi<\/h3>\n<ul>\n<li><strong>Completamente conforme per una spedizione facile:<\/strong> approvato dalle Poste e da DPD per una spedizione affidabile e senza problemi.<\/li>\n<li><strong>Diversi formati di prodotto:<\/strong> scegli tra le opzioni a bottiglia singola, doppia, tripla, quattro, sei o dodici bottiglie per soddisfare le tue specifiche esigenze di confezionamento<\/li>\n<li><strong>Protezione superiore: gli<\/strong> inserti in polpa di cellulosa stampata combinati con i cartoni esterni a doppia parete offrono una protezione eccellente, evitando di danneggiare le bottiglie di birra e le lattine durante il trasporto.<\/li>\n<li><strong>Economico:<\/strong> riduce il rischio di rotture e danni, facendoti risparmiare sui costi di sostituzione e migliorando la redditivit\u00e0 complessiva.<\/li>\n<li><strong>100 % biodegradabile:<\/strong> realizzato con carta riciclata, il nostro imballaggio \u00e8 completamente biodegradabile e contribuisce a un futuro pi\u00f9 sostenibile.<\/li>\n<li><strong>Facile da smaltire:<\/strong> le confezioni possono essere smaltite senza problemi nella carta.<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;594&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;custom&#8221; max_width_custom=&#8221;200px&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; color_override=&#8221;#92bdd9&#8243; solid_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;none&#8221; text=&#8221;Scarica la scheda prodotto&#8221; url=&#8221;https:\/\/www.pulp-tec.com\/wp-content\/uploads\/2025\/06\/postal_bottle_packaging_uk_04.pdf&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;1%&#8221; left_padding_desktop=&#8221;12%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;12%&#8221; left_padding_tablet=&#8221;0&#8243; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;0&#8243; left_padding_phone=&#8221;0&#8243; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#000000&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;center&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Variazioni di prodotto&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;3%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;599&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;custom&#8221; box_shadow=&#8221;none&#8221; top_left_border_radius=&#8221;200&#8243; top_right_border_radius=&#8221;200&#8243; bottom_right_border_radius=&#8221;200&#8243; bottom_left_border_radius=&#8221;200&#8243; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; text_color=&#8221;#000000&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Confezione da una singola bottiglia&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<table class=\"contenttable\">\n<tbody>\n<tr>\n<td class=\"pr-3\"><strong>Lunghezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Larghezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Altezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Peso<\/strong><\/td>\n<td class=\"pr-3\"><strong>Pezzi per pallet<\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"pr-3\">420 mm<\/td>\n<td class=\"pr-3\">115 mm<\/td>\n<td class=\"pr-3\">130 mm<\/td>\n<td class=\"pr-3\">277 g<\/td>\n<td class=\"pr-3\">750 set<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;3%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;604&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;custom&#8221; box_shadow=&#8221;none&#8221; top_left_border_radius=&#8221;200&#8243; top_right_border_radius=&#8221;200&#8243; bottom_right_border_radius=&#8221;200&#8243; bottom_left_border_radius=&#8221;200&#8243; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; text_color=&#8221;#000000&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Confezione da quattro bottiglie&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<table class=\"contenttable\">\n<tbody>\n<tr>\n<td class=\"pr-3\"><strong>Lunghezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Larghezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Altezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Peso<\/strong><\/td>\n<td class=\"pr-3\"><strong>Pezzi per pallet<\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"pr-3\">420 mm<\/td>\n<td class=\"pr-3\">230 mm<\/td>\n<td class=\"pr-3\">260 mm<\/td>\n<td class=\"pr-3\">800 g<\/td>\n<td class=\"pr-3\">300 set<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;3%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;602&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;custom&#8221; box_shadow=&#8221;none&#8221; top_left_border_radius=&#8221;200&#8243; top_right_border_radius=&#8221;200&#8243; bottom_right_border_radius=&#8221;200&#8243; bottom_left_border_radius=&#8221;200&#8243; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; text_color=&#8221;#000000&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Confezione doppia di bottiglie&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<table class=\"contenttable\">\n<tbody>\n<tr>\n<td class=\"pr-3\"><strong>Lunghezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Larghezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Altezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Peso<\/strong><\/td>\n<td class=\"pr-3\"><strong>Pezzi per pallet<\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"pr-3\">420 mm<\/td>\n<td class=\"pr-3\">230 mm<\/td>\n<td class=\"pr-3\">130 mm<\/td>\n<td class=\"pr-3\">456 g<\/td>\n<td class=\"pr-3\">410 set<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;3%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;601&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;custom&#8221; box_shadow=&#8221;none&#8221; top_left_border_radius=&#8221;200&#8243; top_right_border_radius=&#8221;200&#8243; bottom_right_border_radius=&#8221;200&#8243; bottom_left_border_radius=&#8221;200&#8243; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; text_color=&#8221;#000000&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Confezione da sei bottiglie&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<table class=\"contenttable\">\n<tbody>\n<tr>\n<td class=\"pr-3\"><strong>Lunghezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Larghezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Altezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Peso<\/strong><\/td>\n<td class=\"pr-3\"><strong>Pezzi per pallet<\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"pr-3\">420 mm<\/td>\n<td class=\"pr-3\">350 mm<\/td>\n<td class=\"pr-3\">260 mm<\/td>\n<td class=\"pr-3\">1176 g<\/td>\n<td class=\"pr-3\">165 set<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;3%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;603&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;custom&#8221; box_shadow=&#8221;none&#8221; top_left_border_radius=&#8221;200&#8243; top_right_border_radius=&#8221;200&#8243; bottom_right_border_radius=&#8221;200&#8243; bottom_left_border_radius=&#8221;200&#8243; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; text_color=&#8221;#000000&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Confezione da tre bottiglie&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<table class=\"contenttable\">\n<tbody>\n<tr>\n<td class=\"pr-3\"><strong>Lunghezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Larghezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Altezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Peso<\/strong><\/td>\n<td class=\"pr-3\"><strong>Pezzi per pallet<\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"pr-3\">420 mm<\/td>\n<td class=\"pr-3\">350 mm<\/td>\n<td class=\"pr-3\">130 mm<\/td>\n<td class=\"pr-3\">659 g<\/td>\n<td class=\"pr-3\">350 set<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;3%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;600&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;custom&#8221; box_shadow=&#8221;none&#8221; top_left_border_radius=&#8221;200&#8243; top_right_border_radius=&#8221;200&#8243; bottom_right_border_radius=&#8221;200&#8243; bottom_left_border_radius=&#8221;200&#8243; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; text_color=&#8221;#000000&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Confezione da dodici bottiglie&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<table class=\"contenttable\">\n<tbody>\n<tr>\n<td class=\"pr-3\"><strong>Lunghezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Larghezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Altezza<\/strong><\/td>\n<td class=\"pr-3\"><strong>Peso<\/strong><\/td>\n<td class=\"pr-3\"><strong>Pezzi per pallet<\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"pr-3\">800 mm<\/td>\n<td class=\"pr-3\">600 mm<\/td>\n<td class=\"pr-3\">130 mm<\/td>\n<td class=\"pr-3\">2000 g<\/td>\n<td class=\"pr-3\">95 set<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; bottom_padding=&#8221;7%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.95&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_color=&#8221;#eaf1fd&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;50%&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;straight_section&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;5px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_t_to_right_b&#8221; overlay_strength=&#8221;0.8&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;zoom-out-reveal&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Se desideri prezzi, campioni o ulteriore assistenza,<br \/>contatta il nostro team di vendita.[\/vc_column_text][nectar_btn size=&#8221;jumbo&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; color_override=&#8221;#28a745&#8243; solid_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;none&#8221; text=&#8221;Contatta il team vendite&#8221; url=&#8221;mailto:sales-uk@pulp-tec.com&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Se hai una richiesta di sviluppo specifica,<br \/>consulta anche i nostri prodotti personalizzati.[\/vc_column_text][nectar_btn size=&#8221;jumbo&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; color_override=&#8221;#92bdd9&#8243; solid_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;none&#8221; text=&#8221;Prodotti personalizzati&#8221; url=&#8221;https:\/\/www.pulp-tec.com\/custom-pulp-products\/&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;85&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;1%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3092,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-2881","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Imballaggio del vino - Pulp-Tec<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-standard\/imballaggio-del-vino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imballaggio del vino - Pulp-Tec\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;1%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-standard\/imballaggio-del-vino\/\" \/>\n<meta property=\"og:site_name\" content=\"Pulp-Tec\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-09T16:48:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"20 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/prodotti-di-cellulosa-standard\\\/imballaggio-del-vino\\\/\",\"url\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/prodotti-di-cellulosa-standard\\\/imballaggio-del-vino\\\/\",\"name\":\"Imballaggio del vino - Pulp-Tec\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/#website\"},\"datePublished\":\"2025-06-26T15:10:49+00:00\",\"dateModified\":\"2026-04-09T16:48:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/prodotti-di-cellulosa-standard\\\/imballaggio-del-vino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/prodotti-di-cellulosa-standard\\\/imballaggio-del-vino\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/prodotti-di-cellulosa-standard\\\/imballaggio-del-vino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti di cellulosa standard\",\"item\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/prodotti-di-cellulosa-standard\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Imballaggio del vino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/\",\"name\":\"Pulp-Tec\",\"description\":\"Moulded Pulp\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/#organization\",\"name\":\"Pulp-Tec\",\"url\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pulp-tec.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/pulp-tec-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.pulp-tec.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/pulp-tec-logo.svg\",\"width\":62,\"height\":70,\"caption\":\"Pulp-Tec\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pulp-tec\\\/?originalSubdomain=de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Imballaggio del vino - Pulp-Tec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-standard\/imballaggio-del-vino\/","og_locale":"it_IT","og_type":"article","og_title":"Imballaggio del vino - Pulp-Tec","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;1%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;...","og_url":"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-standard\/imballaggio-del-vino\/","og_site_name":"Pulp-Tec","article_modified_time":"2026-04-09T16:48:35+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"20 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-standard\/imballaggio-del-vino\/","url":"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-standard\/imballaggio-del-vino\/","name":"Imballaggio del vino - Pulp-Tec","isPartOf":{"@id":"https:\/\/www.pulp-tec.com\/it\/#website"},"datePublished":"2025-06-26T15:10:49+00:00","dateModified":"2026-04-09T16:48:35+00:00","breadcrumb":{"@id":"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-standard\/imballaggio-del-vino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-standard\/imballaggio-del-vino\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-standard\/imballaggio-del-vino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.pulp-tec.com\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti di cellulosa standard","item":"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-standard\/"},{"@type":"ListItem","position":3,"name":"Imballaggio del vino"}]},{"@type":"WebSite","@id":"https:\/\/www.pulp-tec.com\/it\/#website","url":"https:\/\/www.pulp-tec.com\/it\/","name":"Pulp-Tec","description":"Moulded Pulp","publisher":{"@id":"https:\/\/www.pulp-tec.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pulp-tec.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.pulp-tec.com\/it\/#organization","name":"Pulp-Tec","url":"https:\/\/www.pulp-tec.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pulp-tec.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.pulp-tec.com\/wp-content\/uploads\/2025\/06\/pulp-tec-logo.svg","contentUrl":"https:\/\/www.pulp-tec.com\/wp-content\/uploads\/2025\/06\/pulp-tec-logo.svg","width":62,"height":70,"caption":"Pulp-Tec"},"image":{"@id":"https:\/\/www.pulp-tec.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/pulp-tec\/?originalSubdomain=de"]}]}},"_links":{"self":[{"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/pages\/2881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/comments?post=2881"}],"version-history":[{"count":2,"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/pages\/2881\/revisions"}],"predecessor-version":[{"id":2892,"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/pages\/2881\/revisions\/2892"}],"up":[{"embeddable":true,"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/pages\/3092"}],"wp:attachment":[{"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/media?parent=2881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}