{"id":2928,"date":"2025-06-23T17:00:55","date_gmt":"2025-06-23T15:00:55","guid":{"rendered":"https:\/\/www.pulp-tec.com\/mobili\/"},"modified":"2026-04-09T18:48:37","modified_gmt":"2026-04-09T16:48:37","slug":"mobili","status":"publish","type":"page","link":"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-personalizzati\/mobili\/","title":{"rendered":"Mobili"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h1&#8243; text_color=&#8221;#719fb9&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Mobili&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3 class=\"hl-sub text-pulpdark\">Progettato per l&#8217;eternit\u00e0, realizzato per la finezza<\/h3>\n<p>Noi di Pulp-Tec siamo specializzati nella progettazione e nello sviluppo di mobili che incarnano i principi di un&#8217;economia realmente circolare. Oltre alle nostre soluzioni di arredamento, forniamo imballaggi protettivi che garantiscono un trasporto sicuro, utilizzando materiali sostenibili per ridurre al minimo l&#8217;impatto ambientale. <\/p>\n<p>I nostri prodotti sono pratici, ecologici e dal design estetico. Lavoriamo a stretto contatto con i nostri clienti per creare soluzioni eleganti e sostenibili.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_gallery css=&#8221;&#8221; type=&#8221;flickity_static_height_style&#8221; images=&#8221;2951,2950,2949,2947,2944,2943,2942,2940,2939,2938,2937,2935,2933,2932,2931,2929&#8243; flickity_spacing=&#8221;default&#8221; flickity_controls=&#8221;none&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_autoplay=&#8221;true&#8221; flickity_box_shadow=&#8221;none&#8221; image_loading=&#8221;lazy-load&#8221; onclick=&#8221;link_image&#8221; flickity_img_height=&#8221;400&#8243; flickity_autoplay_dur=&#8221;2000&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3 class=\"\">Vantaggi<\/h3>\n<ul>\n<li><strong>100 % biodegradabile:<\/strong> realizzati con carta riciclata, i nostri prodotti in pasta stampata sono completamente biodegradabili e contribuiscono a un futuro pi\u00f9 sostenibile.<\/li>\n<li><strong>Riciclabile al 100%:<\/strong> i cuscini in polpa di cellulosa possono essere smaltiti senza problemi tra i rifiuti cartacei, offrendo una soluzione semplice ed ecologica agli utenti finali.<\/li>\n<li>Design personalizzato: il nostro team di sviluppo adatta perfettamente la forma dell&#8217;imballaggio in polpa di cellulosa alla tua merce imballata, garantendo cos\u00ec la migliore protezione e un&#8217;ottima esperienza di unboxing da parte del cliente.<\/li>\n<li><strong>Tutto in uno:<\/strong> Pulp-Tec \u00e8 in grado di supportarti durante l&#8217;intero processo: grazie al nostro team di esperti di progettazione, all&#8217;attrezzeria interna e alle molteplici tecnologie di produzione, siamo in grado di offrire il massimo servizio per implementare con successo e rapidamente nuove soluzioni di imballaggio personalizzate. (Qui trovi l&#8217;intero processo di sviluppo del prodotto) <\/li>\n<li><strong>Riduzione dei costi: <\/strong>grazie alla nidificabilit\u00e0 dei prodotti, \u00e8 possibile stoccare fino al 60% di prodotti in pi\u00f9 su un pallet rispetto al polistirolo, con conseguente riduzione dei costi di stoccaggio, trasporto e prelievo.<\/li>\n<li><strong>Bassa volatilit\u00e0: <\/strong>i nostri prodotti sono privi di petrolio e quindi hanno una bassa volatilit\u00e0 dei prezzi<strong>. <\/strong><\/li>\n<li><strong>Riduzione dei danni da trasporto: <\/strong>il design sicuro e stabile aiuta a proteggere i materiali, riducendo il rischio di danni durante il trasporto<strong>. <\/strong><\/li>\n<li><strong>Opzione idrorepellente: <\/strong>a seconda dell&#8217;applicazione, \u00e8 possibile aggiungere additivi alla cera per la resistenza all&#8217;umidit\u00e0, proteggendo i materiali dall&#8217;umidit\u00e0 e rendendo possibile il trasporto all&#8217;estero.<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;115&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;custom&#8221; max_width_custom=&#8221;350px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.95&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_color=&#8221;#eaf1fd&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;50%&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;straight_section&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;5px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_t_to_right_b&#8221; overlay_strength=&#8221;0.8&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;zoom-out-reveal&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Hai un prodotto specifico che desideri sviluppare? Contatta il nostro team di vendita, saremo lieti di aiutarti.[\/vc_column_text][nectar_btn size=&#8221;jumbo&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; color_override=&#8221;#28a745&#8243; solid_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;none&#8221; text=&#8221;Contatta il team vendite&#8221; url=&#8221;mailto:sales-uk@pulp-tec.com&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#000000&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Nel nostro portafoglio prodotti puoi trovare anche un&#8217;ampia gamma di confezioni di bottiglie di pasta di cellulosa standard immediatamente disponibili.[\/vc_column_text][nectar_btn size=&#8221;jumbo&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; color_override=&#8221;#719fb9&#8243; solid_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;none&#8221; text=&#8221;Prodotti standard&#8221; url=&#8221;https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-standard\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;66&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3094,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-2928","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mobili - Pulp-Tec<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-personalizzati\/mobili\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mobili - Pulp-Tec\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-personalizzati\/mobili\/\" \/>\n<meta property=\"og:site_name\" content=\"Pulp-Tec\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-09T16:48:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/prodotti-di-cellulosa-personalizzati\\\/mobili\\\/\",\"url\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/prodotti-di-cellulosa-personalizzati\\\/mobili\\\/\",\"name\":\"Mobili - Pulp-Tec\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/#website\"},\"datePublished\":\"2025-06-23T15:00:55+00:00\",\"dateModified\":\"2026-04-09T16:48:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/prodotti-di-cellulosa-personalizzati\\\/mobili\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/prodotti-di-cellulosa-personalizzati\\\/mobili\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/prodotti-di-cellulosa-personalizzati\\\/mobili\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti di cellulosa personalizzati\",\"item\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/prodotti-di-cellulosa-personalizzati\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mobili\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/\",\"name\":\"Pulp-Tec\",\"description\":\"Moulded Pulp\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/#organization\",\"name\":\"Pulp-Tec\",\"url\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pulp-tec.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/pulp-tec-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.pulp-tec.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/pulp-tec-logo.svg\",\"width\":62,\"height\":70,\"caption\":\"Pulp-Tec\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pulp-tec.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pulp-tec\\\/?originalSubdomain=de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mobili - Pulp-Tec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-personalizzati\/mobili\/","og_locale":"it_IT","og_type":"article","og_title":"Mobili - Pulp-Tec","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;...","og_url":"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-personalizzati\/mobili\/","og_site_name":"Pulp-Tec","article_modified_time":"2026-04-09T16:48:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-personalizzati\/mobili\/","url":"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-personalizzati\/mobili\/","name":"Mobili - Pulp-Tec","isPartOf":{"@id":"https:\/\/www.pulp-tec.com\/it\/#website"},"datePublished":"2025-06-23T15:00:55+00:00","dateModified":"2026-04-09T16:48:37+00:00","breadcrumb":{"@id":"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-personalizzati\/mobili\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-personalizzati\/mobili\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-personalizzati\/mobili\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.pulp-tec.com\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti di cellulosa personalizzati","item":"https:\/\/www.pulp-tec.com\/it\/prodotti-di-cellulosa-personalizzati\/"},{"@type":"ListItem","position":3,"name":"Mobili"}]},{"@type":"WebSite","@id":"https:\/\/www.pulp-tec.com\/it\/#website","url":"https:\/\/www.pulp-tec.com\/it\/","name":"Pulp-Tec","description":"Moulded Pulp","publisher":{"@id":"https:\/\/www.pulp-tec.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pulp-tec.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.pulp-tec.com\/it\/#organization","name":"Pulp-Tec","url":"https:\/\/www.pulp-tec.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pulp-tec.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.pulp-tec.com\/wp-content\/uploads\/2025\/06\/pulp-tec-logo.svg","contentUrl":"https:\/\/www.pulp-tec.com\/wp-content\/uploads\/2025\/06\/pulp-tec-logo.svg","width":62,"height":70,"caption":"Pulp-Tec"},"image":{"@id":"https:\/\/www.pulp-tec.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/pulp-tec\/?originalSubdomain=de"]}]}},"_links":{"self":[{"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/pages\/2928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/comments?post=2928"}],"version-history":[{"count":5,"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/pages\/2928\/revisions"}],"predecessor-version":[{"id":3102,"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/pages\/2928\/revisions\/3102"}],"up":[{"embeddable":true,"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/pages\/3094"}],"wp:attachment":[{"href":"https:\/\/www.pulp-tec.com\/it\/wp-json\/wp\/v2\/media?parent=2928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}